{"id":2619,"date":"2019-04-03T09:16:11","date_gmt":"2019-04-03T07:16:11","guid":{"rendered":"https:\/\/www.agec.it\/cimiteromonumentale\/?page_id=2619"},"modified":"2022-08-23T15:02:14","modified_gmt":"2022-08-23T13:02:14","slug":"informativa-privacy","status":"publish","type":"page","link":"https:\/\/www.agec.it\/cimiteromonumentale\/info-e-contatti\/informativa-privacy\/","title":{"rendered":"Informativa sul trattamento dei dati personali"},"content":{"rendered":"<p><b>Trattamento dei dati personali<br \/>\n<\/b>Agec &#8211; Azienda Gestione Edifici Comunali del Comune di Verona (in seguito Agec) in qualit\u00e0 di Titolare del Trattamento dei Dati Personali, Vi informa che l\u2019accesso al proprio sito web e\/o eventuali richieste di informazioni o di servizi comportano la raccolta di dati personali che saranno oggetto di trattamento nel pieno rispetto del Regolamento UE 2016\/679 (<u>di seguito \u201c<b>RGPD<\/b>\u201d<\/u>) e del D.Lgs. n. 196\/2003 come novellato dal D.Lgs. n. 101\/2018. Attraverso tale informativa gli Utenti potranno conoscere, in maniera preventiva, le modalit\u00e0 di trattamento necessarie all\u2019utilizzo di alcune aree dei siti web di Agec.<\/p>\n<div>\n<p><span style=\"font-family: Merriweather Sans;\">Ai sensi della predetta normativa, tale trattamento sar\u00e0 improntato ai principi di correttezza, liceit\u00e0 e trasparenza, tutelando la Vostra riservatezza ed i Vostri diritti.<\/span><\/p>\n<div><span style=\"font-family: Merriweather Sans;\">\u00a0<\/span><\/div>\n<div>\n<h2><span style=\"font-family: Merriweather Sans;\">INFORMATIVA PRIVACY<\/span><\/h2>\n<p><span style=\"font-family: Merriweather Sans;\"><b>1. Titolare del trattamento, RPD, Responsabile del trattamento ex art. 28 RGPD<\/b><\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\">Titolare del trattamento dei dati \u00e8 AGEC, con sede in Via Enrico Noris n. 1 &#8211; 37121 Verona, tel. +39 045 8051311, e-mail:\u00a0<a title=\"\" href=\"mailto:infoagec@agec.it\" target=\"\" rel=\"noopener\">infoagec@agec.it<\/a>\u00a0, PEC:\u00a0\u00a0<a title=\"\" href=\"mailto:infoagec@pec.agec.it\" target=\"\" rel=\"noopener\">infoagec@pec.agec.it<\/a><br \/>\n<\/span>I dati di contatto del Responsabile della Protezione dei Dati (RPD o \u201cDPO\u201d) sono i seguenti: Via Enrico Noris n. 1 &#8211; 37121 Verona, tel. +39 045 8051311, e-mail:\u00a0<a title=\"\" href=\"mailto:rpd.privacy@agec.it\" target=\"\" rel=\"noopener\">rpd.privacy@agec.it<\/a>\u00a0, PEC:\u00a0\u00a0<a title=\"\" href=\"mailto:infoagec@pec.agec.it\" target=\"\" rel=\"noopener\">infoagec@pec.agec.it<\/a><br \/>\nIl Responsabile del trattamento dei dati ai sensi dell\u2019art. 28 del RGPD, per le attivit\u00e0 di manutenzione dei siti web di Agec, \u00e8 Lime &amp; Co. S.r.l., sede legale in Verona, Via Colonnello Fincato n. 214, tel. +390454951626, e-mail\u00a0<a title=\"\" href=\"mailto:info@limeandco.it\" target=\"\" rel=\"noopener\">info@limeandco.it<\/a>\u00a0e\u00a0<a title=\"\" href=\"mailto:amministrazione@limesolutions.it\" target=\"\" rel=\"noopener\">amministrazione@limesolutions.it<\/a><\/p>\n<p><b>2. Finalit\u00e0 e basi giuridiche del trattamento<\/b><br \/>\nSecondo le esigenze di volta in volta manifestate dall\u2019Utente che accede alle varie sezioni del Sito (e salvo norme e informative particolari per singole operazioni che comportino il conferimento di specifici dati personali, pubblicate di volta in volta sul Sito), di seguito sono indicate\u00a0<u>le finalit\u00e0 del trattamento dei dati personali<\/u>, conferiti direttamente dagli Utenti o acquisiti automaticamente mediante la navigazione:<\/p>\n<\/div>\n<\/div>\n<ul>\n<li>erogare e gestire i vari servizi offerti;<\/li>\n<li>personalizzare l\u2019esperienza degli Utenti sul Sito e migliorare servizi offerti da Agec alla propria utenza, nel rispetto dei requisiti di legge;<\/li>\n<li>rispondere alle richieste degli Utenti in relazione a servizi svolti da Agec;<\/li>\n<li>consentire agli utenti di intervenire e interagire su siti di propriet\u00e0 di Terze Parti con le quali AGEC abbia attivato le relative funzioni di collegamento, quali, a titolo esemplificativo e non esaustivo, social network quali Facebook ed Instagram (di seguito \u201cSocial Network\u201d).<\/li>\n<\/ul>\n<blockquote>\n<div><\/div>\n<\/blockquote>\n<div>\n<div>\n<p>Al fine di evadere le eventuali richieste riguardanti i servizi offerti, gli Utenti saranno invitati a conferire dati personali, che saranno trattati per le sole relative finalit\u00e0 e per il tempo strettamente necessario.<\/p>\n<p><u>Basi giuridiche del trattamento<\/u>: l\u2019esecuzione di un compito di interesse pubblico o connesso all\u2019esercizio di pubblici poteri di cui \u00e8 investito il Titolare del trattamento, ai sensi dell\u2019art. 6, paragrafo 1, lettera e) del Regolamento UE 2016\/679; l\u2019adempimento di un obbligo legale al quale \u00e8 soggetto il Titolare del trattamento, ai sensi dell\u2019art. 6, paragrafo 1, lettera c) del Regolamento UE 2016\/679.<\/p>\n<p><b>3. Categorie di dati personali oggetto di trattamento<\/b><br \/>\nOltre ai Dati Personali conferiti direttamente dagli Utenti (quali nome, cognome, indirizzo postale, di posta elettronica, ecc.) mediante la compilazione dei moduli on-line oppure l\u2019accesso diretto, tramite link, all\u2019indirizzo di posta elettronica di Agec, durante la connessione i sistemi informatici e le procedure software preposte al funzionamento del Sito acquisiscono automaticamente ed indirettamente alcune informazioni che potrebbero costituire dati personali, la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet, quali, in via esemplificativa e non esaustiva, i c.d. \u201ccookie\u201d (come di seguito specificato), indirizzi \u201cIP\u201d, nome pc dei computer utilizzati dagli Utenti che si connettono al Sito, indirizzi in notazione \u201cUrl\u201d delle risorse richieste, orario della richiesta al server, navigazione sul Sito.<\/p>\n<p><b>4. Modalit\u00e0 del trattamento<\/b><br \/>\nPer trattamento dei dati si intende qualsiasi operazione o complesso di operazioni, svolti con o senza ausilio di mezzi elettronici o comunque automatizzati, riguardanti la raccolta, la registrazione, l\u2019organizzazione, la conservazione, l\u2019elaborazione, la modificazione, l\u2019estrazione, il raffronto, l\u2019utilizzo, la comunicazione, la diffusione, l\u2019interconnessione, il blocco, la cancellazione, la distruzione e la selezione dei dati stessi.<\/p>\n<p>I dati personali saranno trattati in forma prevalentemente automatizzata ma anche cartacea, con logiche strettamente correlate alle predette finalit\u00e0, mediante i Data Base, le Piattaforme elettroniche gestite da Agec o da terzi nominati responsabili del trattamento, sistemi integrati di natura informatica e\/o siti web di titolarit\u00e0 o in uso ad Agec.<\/p>\n<p>Il Titolare ha adottato idonee misure di sicurezza per proteggere gli Utenti contro il rischio di perdita, abuso o alterazione dei Dati. In particolare: ha adottato le misure di cui all\u2019art. 32 del RGPD; utilizza i protocolli protetti di trasmissione dei dati noti come HTTPS; di norma conserva i dati degli Utenti su server ubicati nel territorio europeo (salvo il caso di particolari piattaforme elettroniche, ad es. Google e i Social Network, che potrebbero comportare il trasferimento dei dati in USA). I server sono soggetti a un sistema avanzato e quotidiano di back up e disaster recovery.<\/p>\n<p><b>5. Natura e modalit\u00e0 del conferimento dei dati personali degli Utenti, conseguenze del mancato conferimento<\/b><br \/>\nIl conferimento di dati personali \u00e8 generalmente facoltativo, essendo obbligatorio soltanto per i dati personali i cui campi sono evidenziati in fase di inserimento, o altrimenti contrassegnati come obbligatori affinch\u00e9\u0301 Agec possa soddisfare le esigenze dell\u2019Utente nell\u2019ambito delle funzionalit\u00e0 del Sito. Il mancato, parziale o inesatto conferimento dei dati personali che siano necessari per l\u2019esecuzione della prestazione richiesta, comporta l\u2019impossibilit\u00e0 di eseguire la prestazione richiesta; mentre il mancato, parziale o inesatto conferimento dei dati personali facoltativi non comporta alcuna conseguenza.<\/p>\n<p>Il conferimento dei dati personali pu\u00f2 avvenire mediante la compilazione degli appositi campi nelle varie sezioni del Sito, oppure con l\u2019invio delle richieste a mezzo e-mail ove previsto.<\/p>\n<p><b>6. Periodo di conservazione dei dati personali<\/b><br \/>\nI dati comunicati, se di rilevanza giuridico probatoria, sono protocollati ed archiviati digitalmente, anche su supporto cartaceo qualora si renda necessario. Essi saranno conservati per il tempo strettamente necessario a fornire il servizio richiesto dall\u2019Utente e, in caso di contenzioso, per la durata del medesimo, nel rispetto dei tempi massimi di conservazione specificati dal \u201cRegolamento per l\u2019archivio dell\u2019Agec\u201d e dal \u201cManuale di Gestione del Protocollo Informatico (Dpcm 3.12.2013, artt. 3 e 5)\u201d, entrambi consultabili sul sito web aziendale. Attualmente il tempo massimo di conservazione per reclami\/lamentele\/richieste e relativi riscontri \u00e8 stabilito in cinque anni (corrispondente al termine di prescrizione del risarcimento da fatto illecito ex art. 2947 codice civile).<\/p>\n<p><b>7. Luogo del trattamento<\/b><br \/>\nI dati personali sono trattati principalmente presso la sede legale del Titolare in Verona, in Via Enrico Noris n. 1. Per ulteriori informazioni, gli Utenti possono interpellare il Titolare ai contatti sopra indicati.<\/p>\n<p><b>8. Categorie di destinatari dei dati personali degli Utenti<\/b><br \/>\nI dati personali potranno essere portati a conoscenza di dipendenti o ausiliari del Titolare che, operando sotto la diretta autorit\u00e0 di quest\u2019ultimo, trattano dati e sono designati Amministratori di sistema o referenti interni, o comunque sono autorizzati al trattamento ed istruiti dal Titolare ai sensi degli artt. 24 e 29 del RGPD (a titolo esemplificativo e non esaustivo, addetti al reparto informatico, al Servizio Posta e Gestione documentale, all\u2019URP, all\u2019Ufficio Legale, ecc.).<\/p>\n<p>Potranno altres\u00ec venire a conoscenza dei dati personali i Responsabili del trattamento ex art. 28 del RGPD, che svolgano attivit\u00e0 in outsourcing per conto di Agec (a titolo esemplificativo e non esaustivo, soggetti a cui venga affidata attivit\u00e0 di assistenza, comunicazione o promozione, gestori di siti o di piattaforme elettroniche, fornitori di servizi IT, ecc.).<\/p>\n<p><b>9. Diffusione dei dati personali degli Utenti<\/b><br \/>\nI dati personali non saranno diffusi a terzi.<\/p>\n<p><b>10. Trasferimento extra UE dei dati personali degli Utenti<\/b><br \/>\nI dati personali che vengano registrati su siti di propriet\u00e0 di Terze Parti (ad es., Social Network) sono condivisi con soggetti che si potrebbero trovare al di fuori dello Spazio Economico Europeo. Il trattamento dei dati personali da parte di questi soggetti \u00e8 regolamentato da appositi strumenti giuridici (quali decisioni di adeguatezza, clausole contrattuali tipo approvate dalla Commissione Europea, ecc.).<\/p>\n<p><b>11. Minori<\/b><br \/>\nIl sito non contiene alcuna informazione destinata direttamente ai minori. I minori non devono conferire informazioni o dati personali ad Agec in difetto del consenso degli esercenti la responsabilit\u00e0 genitoriale, tutori o curatori. Pertanto, Agec invita tutti coloro che esercitano la responsabilit\u00e0 genitoriale, la tutela o curatela su minori ad informare ed educare gli stessi riguardo all\u2019utilizzo sicuro e responsabile del Web e degli strumenti informatici, nonch\u00e9 ad osservare le procedure di volta in volta indicate in relazione alle iniziative di Agec che possano includere il trattamento di dati personali di minori.<\/p>\n<p><b>12. Diritti degli Utenti<\/b><br \/>\nNella qualit\u00e0 di \u201cinteressati\u201d, gli Utenti possono esercitare, nei confronti del Titolare, i diritti di cui agli articoli da 15 a 22 del Regolamento UE 2016\/679.<\/p>\n<p>Nello specifico:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>il diritto di accesso: per ottenere la conferma o meno di dati personali che lo riguardano e di ottenere l\u2019accesso a tali dati e a specifiche informazioni (ad es. finalit\u00e0 del trattamento, categorie dei dati in questione, i destinatari a cui i dati saranno comunicati);<\/li>\n<li>il diritto di rettifica: di ottenere la rettifica dei dati inesatti che lo riguardano senza ingiustificato ritardo. In tal caso sorge l\u2019obbligo da parte del titolare del trattamento di comunicare la rettifica a tutti i destinatari cui sono stati trasmessi i dati, salvo che ci\u00f2 non implichi uno sforzo sproporzionato;<\/li>\n<li>il diritto alla cancellazione: per ottenere la cancellazione dei dati che lo riguardano senza ingiustificato ritardo e il titolare del trattamento ha l\u2019obbligo di cancellarli senza ingiustificato ritardo se sussistono determinati motivi (ad es. i dati personali non sono pi\u00f9 necessari rispetto alle finalit\u00e0 per cui erano stati raccolti; se l\u2019interessato revoca il consenso; se devono essere cancellati per un obbligo legale). In tal caso sorge l\u2019obbligo da parte del titolare del trattamento di comunicare la cancellazione a tutti i destinatari cui sono stati trasmessi i dati, salvo che ci\u00f2 non implichi uno sforzo sproporzionato;<\/li>\n<li>il diritto di limitazione del trattamento: si pu\u00f2 disporre al titolare del trattamento una restrizione al trattamento dei dati, ad esempio alla sola conservazione con esclusione di qualsiasi altro utilizzo, in determinate ipotesi (ad es. se il trattamento \u00e8 illecito e l\u2019interessato si oppone alla cancellazione dei dati; se l\u2019interessato contesta l\u2019esattezza, nei limiti del periodo di verifica dell\u2019esattezza). In tal caso sorge l\u2019obbligo da parte del titolare del trattamento di comunicare la limitazione del trattamento a tutti i destinatari cui sono stati trasmessi i dati, salvo che ci\u00f2 non implichi uno sforzo sproporzionato;<\/li>\n<li>il diritto alla portabilit\u00e0 dei dati: per ottenere la restituzione dei dati personali forniti e trasmetterli ad altri o per chiedere la trasmissione da un titolare all\u2019altro, se tecnicamente fattibile;<\/li>\n<li>il diritto di opposizione: per opporsi in qualsiasi momento al trattamento per scopi di interesse pubblico o per legittimo interesse; per finalit\u00e0 di marketing; per fini di ricerca scientifica, storica o statistica;<\/li>\n<li>il diritto di non essere sottoposto a una decisione basata unicamente sul trattamento automatizzato, compresa la profilazione, che produca effetti giuridici che lo riguardano o che incida in modo analogo significativamente sulla sua persona.<\/li>\n<\/ul>\n<p>Gli Utenti hanno diritto di proporre reclamo al Garante per la Protezione dei Dati Personali, Piazza Monte Citorio 121 &#8211; 00186 Roma, quale Autorit\u00e0 di controllo nazionale (art. 77 del RGPD), o semplicemente contattare il Garante per avere informazioni inerenti all\u2019esercizio dei propri diritti derivanti dal RGPD.<\/p>\n<\/div>\n<div>\n<h2>COOKIE POLICY<\/h2>\n<p><span style=\"font-family: Merriweather Sans;\"><b>1. Funzione dei Cookie<br \/>\n<\/b><\/span>I cookie sono menzionati nel Considerando n. 30 del Regolamento UE 2016\/679:\u00a0<i>\u201cLe persone fisiche possono essere associate a identificativi online prodotti dai dispositivi, dalle applicazioni, dagli strumenti e dai protocolli utilizzati, quali gli indirizzi IP, marcatori temporanei (<b>cookies<\/b>) o identificativi di altro tipo, quali i tag di identificazione a radiofrequenza. Tali identificativi possono lasciare tracce che, in particolare se combinate con identificativi univoci e altre informazioni ricevute dai server, possono essere utilizzate per creare profili delle persone fisiche e identificarle\u201d.<br \/>\n<\/i>I cookie sono di regola stringhe di testo che i siti web (cd. Publisher, o \u201cprime parti\u201d) visitati dall\u2019utente ovvero siti o web server diversi (cd. \u201cterze parti\u201d) posizionano ed archiviano \u2013 direttamente, nel caso dei publisher e indirettamente, cio\u00e8 per il tramite di questi ultimi, nel caso delle \u201cterze parti\u201d &#8211; all\u2019interno di dispositivi terminali nella disponibilit\u00e0 dell\u2019Utente medesimo. Tali dispositivi terminali sono, ad esempio, un computer, un tablet, uno smartphone, ovvero ogni altro dispositivo in grado di archiviare informazioni; tra essi occorre annoverare anche i cd. dispositivi IoT (Internet of Things, o Internet delle cose), i quali sono progettati per connettersi alla rete e tra loro per fornire servizi di varia natura, non necessariamente limitati alla mera comunicazione.<br \/>\nI software per la navigazione in internet e il funzionamento di questi dispositivi, ad esempio i browser, possono memorizzare i cookie e poi trasmetterli nuovamente ai siti che li hanno generati in occasione di una successiva visita del medesimo Utente, mantenendo cos\u00ec memoria della sua precedente interazione con uno o pi\u00f9 siti web.<br \/>\nLe informazioni codificate nei cookie possono includere dati personali, come un indirizzo IP, un nome utente, un identificativo univoco o un indirizzo e-mail, ma possono anche contenere dati non personali, come le impostazioni della lingua o informazioni sul tipo di dispositivo che una persona sta utilizzando per navigare nel sito.<br \/>\nI cookie possono dunque svolgere importanti e diverse funzioni, tra cui il monitoraggio di sessioni, la memorizzazione di informazioni su specifiche configurazioni riguardanti gli Utenti che accedono al server, l\u2019agevolazione nella fruizione dei contenuti online, ecc. (possono, ad esempio, essere impiegati per tenere traccia delle informazioni utilizzate per la compilazione di un modulo informatico).<\/p>\n<p>2.<b>\u00a0<\/b><b>Categorie dei Cookie tecnici utilizzati<br \/>\n<\/b>Ai sensi dell\u2019art. 122 del D.Lgs. n. 196\/2003, il Sito utilizza le seguenti categorie di cookie tecnici:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><span style=\"font-family: Merriweather Sans;\">cookie di sessione necessari o\u00a0<i>\u201cstrictly necessary cookies\u201d<\/i>: sono necessari per la navigazione su un Sito web e l\u2019utilizzo dei suoi servizi, ad esempio per consentire una corretta visualizzazione. Pertanto, la disabilitazione di tali cookie preclude la fruizione \u201cordinaria\u201d del Sito.<\/span><\/li>\n<li><span style=\"font-family: Merriweather Sans;\">cookie di funzionalit\u00e0 o\u00a0<i>\u201cfunctionality cookies\u201d<\/i>: sono utili a supportare alcune funzionalit\u00e0 del Sito, come la velocit\u00e0 di navigazione, mediante caratteri di personalizzazione anche duraturi consistenti nella memorizzazione delle preferenze gi\u00e0 selezionate dall\u2019Utente (come il nome utente, l\u2019impostazione della lingua, dei caratteri e delle dimensioni del testo, ecc.).<\/span><\/li>\n<\/ol>\n<p><span style=\"font-family: Merriweather Sans;\"><b>3. Disabilitazione (\u201copt-out\u201d) per qualunque cookie<br \/>\n<\/b><\/span>L\u2019Utente pu\u00f2 disabilitare (\u201copt-out\u201d) qualunque cookie attivo, anche per i cd. \u201ccookie tecnici\u201d (art. 122 D.Lgs. n. 196\/2003).<br \/>\nLa disabilitazione pu\u00f2 essere eseguita mediante le relative impostazioni del proprio browser (vedasi il paragrafo successivo), oppure accedendo al seguente sito:<\/p>\n<\/div>\n<\/div>\n<ul>\n<li><a title=\"\" href=\"https:\/\/www.youronlinechoices.eu\/\" target=\"\" rel=\"noopener\">www.youronlinechoices.eu<\/a>\u00a0sito web gestito da European Interactive Digital Advertising Alliance (EDAA), per la cancellazione degli altri cookies nel caso degli Utenti con sede nell\u2019Unione Europea, e http:\/\/www.aboutads.info\/choises\/, per la cancellazione degli altri cookies nel caso degli Utenti residenti negli Stati Uniti d\u2019America.<\/li>\n<\/ul>\n<div>\n<div>\n<p><span style=\"font-family: Merriweather Sans;\">Tali siti non sono gestiti da Agec, che non si assume dunque alcuna responsabilit\u00e0 in relazione ai rispettivi contenuti.<\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\"><b>5. Come disabilitare i cookie sui propri browser<br \/>\n<\/b><\/span>Posto che la raccolta dei dati mediante i cookie ha natura facoltativa., l\u2019Utente pu\u00f2 bloccare l\u2019accettazione dei cookie da parte del browser di navigazione. Tuttavia, questa operazione di blocco potrebbe rendere meno efficiente o impedire l\u2019accesso ad alcune funzioni o pagine del Sito.<br \/>\nDi seguito riportiamo le modalit\u00e0 offerte dai principali browser per bloccare l\u2019accettazione dei cookie:<\/p>\n<p><span style=\"font-family: Merriweather Sans;\">Edge:\u00a0<a title=\"\" href=\"https:\/\/support.microsoft.com\/it-it\/windows\/eliminare-e-gestire-i-cookie-168dab11-0753-043d-7c16-ede5947fc64d\" target=\"\" rel=\"noopener\">https:\/\/support.microsoft.com\/it-it\/windows\/eliminare-e-gestire-i-cookie-168dab11-0753-043d-7c16-ede5947fc64d<\/a><\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\">Internet Explorer:\u00a0<a title=\"\" href=\"http:\/\/windows.microsoft.com\/it-it\/internet-explorer\/delete-manage-cookies#ie=ie-11\" target=\"\" rel=\"noopener\">http:\/\/windows.microsoft.com\/it-it\/internet-explorer\/delete-manage-cookies#ie=ie-11<\/a><\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\">Firefox:\u00a0<a title=\"\" href=\"https:\/\/support.mozilla.org\/it\/kb\/Gestione%20dei%20cookie\" target=\"\" rel=\"noopener\">https:\/\/support.mozilla.org\/it\/kb\/Gestione%20dei%20cookie<\/a><\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\">Chrome:\u00a0<a title=\"\" href=\"https:\/\/support.google.com\/chrome\/answer\/95647?hl=it\" target=\"\" rel=\"noopener\">https:\/\/support.google.com\/chrome\/answer\/95647?hl=it<\/a><\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\">Safari:\u00a0<a title=\"\" href=\"http:\/\/support.apple.com\/kb\/HT1677?viewlocale=it_IT\" target=\"\" rel=\"noopener\">http:\/\/support.apple.com\/kb\/HT1677?viewlocale=it_IT<\/a><\/span><\/p>\n<p><span style=\"font-family: Merriweather Sans;\"><b>6. Categorie di destinatari e tempi di conservazione dei dati personali raccolti mediante i cookie<br \/>\n<\/b><\/span>Possono venire a conoscenza dei dati raccolti mediante i cookie gli amministratori di sistema del Titolare Agec, nonch\u00e9 il Responsabile del trattamento dei dati Lime &amp; Co. Srl.<\/p>\n<p>Alcuni cookie sono temporanei (c.d. \u201ccookie di sessione\u201d) e si cancellano in automatico al termine della singola sessione; altri cookie sono \u201cpermanenti\u201d, ossia rimangono memorizzati nei dispositivi che si sono connessi al Sito e rientrano in collegamento attivo ogni volta che l\u2019Utente si riconnette al medesimo.<br \/>\nI tempi di conservazione dei dati personali raccolti mediante i cookie sono partitamente indicati nel seguente prospetto riepilogativo:<\/p>\n<\/div>\n<\/div>\n<table width=\"653\">\n<thead>\n<tr>\n<td><strong>Nome<\/strong><\/td>\n<td><strong>Dominio<\/strong><\/td>\n<td><strong>Scopo<\/strong><\/td>\n<td><strong>Durata<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>\u00a0PHPSESSID<\/td>\n<td>\u00a0AGEC<\/td>\n<td>\u00a0serve a riconoscere tutte le richieste provenienti dallo stesso utente<\/td>\n<td>\u00a0sessione di navigazione<\/td>\n<\/tr>\n<tr>\n<td>\u00a0cookiebar<\/td>\n<td>\u00a0AGEC<\/td>\n<td>\u00a0utilizzato per registrare la scelta dell\u2019utente in merito all\u2019accettazione dei cookie<\/td>\n<td>\u00a0 sessione di navigazione<\/td>\n<\/tr>\n<tr>\n<td>\u00a0pll_language<\/td>\n<td>\u00a0AGEC\\Cimitero Monumentale<\/td>\n<td>\u00a0utilizzato per impostare la lingua e salvare la relativa preferenza di navigazione<\/td>\n<td>\u00a01 anno<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>\n<div><\/div>\n<div><b>7. Piattaforme esterne Social Network<\/b><\/div>\n<div>Il presente sito web contiene link di accesso alla piattaforma esterna del social network\u00a0<b>Facebook<\/b>\u00a0di propriet\u00e0 di Terze Parti, che hanno adottato proprie impostazioni e policy di protezione dei dati personali (vedasi la normativa generale del titolare del trattamento Facebook Ireland Ltd. al link:\u00a0<a title=\"\" href=\"https:\/\/www.facebook.com\/privacy\/explanation\" target=\"\" rel=\"noopener\">https:\/\/www.facebook.com\/privacy\/explanation<\/a>).<\/div>\n<div>Per la piattaforma Facebook, si rinvia al link:\u00a0<a title=\"\" href=\"https:\/\/www.facebook.com\/about\/basics\" target=\"\" rel=\"noopener\">https:\/\/www.facebook.com\/about\/basics<\/a><\/div>\n<div><\/div>\n<div style=\"text-align: center;\">* * * * *<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trattamento dei dati personali Agec &#8211; Azienda Gestione Edifici Comunali del Comune di Verona (in seguito Agec) in qualit\u00e0 di Titolare del Trattamento dei Dati Personali, Vi informa che l\u2019accesso al proprio sito web e\/o eventuali richieste di informazioni o di servizi comportano la raccolta di dati personali che saranno oggetto di trattamento nel pieno [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1019,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"_links":{"self":[{"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/pages\/2619"}],"collection":[{"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/comments?post=2619"}],"version-history":[{"count":8,"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/pages\/2619\/revisions"}],"predecessor-version":[{"id":3631,"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/pages\/2619\/revisions\/3631"}],"up":[{"embeddable":true,"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/pages\/1019"}],"wp:attachment":[{"href":"https:\/\/www.agec.it\/cimiteromonumentale\/wp-json\/wp\/v2\/media?parent=2619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}